{"id":700,"date":"2024-01-10T10:22:47","date_gmt":"2024-01-10T13:22:47","guid":{"rendered":"https:\/\/siticcan.com.br\/ba\/?p=700"},"modified":"2024-01-10T10:22:47","modified_gmt":"2024-01-10T13:22:47","slug":"governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes","status":"publish","type":"post","link":"https:\/\/siticcan.com.br\/ba\/index.php\/2024\/01\/10\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\/","title":{"rendered":"Governo anuncia passagem de avi\u00e3o a R$ 200 para ao menos 3 milh\u00f5es de aposentados e estudantes"},"content":{"rendered":"<figure id=\"attachment_701\" aria-describedby=\"caption-attachment-701\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-701\" src=\"https:\/\/siticcan.com.br\/ba\/wp-content\/uploads\/2024\/01\/silvio-costa-filho_-vosmar-rosa_mpa-900x615-1-300x205.jpg\" alt=\"\" width=\"300\" height=\"205\" srcset=\"https:\/\/siticcan.com.br\/ba\/wp-content\/uploads\/2024\/01\/silvio-costa-filho_-vosmar-rosa_mpa-900x615-1-300x205.jpg 300w, https:\/\/siticcan.com.br\/ba\/wp-content\/uploads\/2024\/01\/silvio-costa-filho_-vosmar-rosa_mpa-900x615-1-768x525.jpg 768w, https:\/\/siticcan.com.br\/ba\/wp-content\/uploads\/2024\/01\/silvio-costa-filho_-vosmar-rosa_mpa-900x615-1-218x150.jpg 218w, https:\/\/siticcan.com.br\/ba\/wp-content\/uploads\/2024\/01\/silvio-costa-filho_-vosmar-rosa_mpa-900x615-1-696x476.jpg 696w, https:\/\/siticcan.com.br\/ba\/wp-content\/uploads\/2024\/01\/silvio-costa-filho_-vosmar-rosa_mpa-900x615-1.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-701\" class=\"wp-caption-text\">Foto: Vosmar Rosa\/MPA\/Arquivo<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">O ministro de Portos e Aeroportos, Silvio Costa Filho, afirmou nesta ter\u00e7a-feira (9) que o programa Voa Brasil disponibilizar\u00e1 passagens a R$ 200 e ser\u00e1 voltado a aposentados do INSS (Instituto Nacional do Seguro Social) que ganham at\u00e9 dois sal\u00e1rios m\u00ednimos e estudantes do Prouni.<\/p>\n<p style=\"text-align: justify;\">O ministro afirmou que esse p\u00fablico equivale a 20,6 milh\u00f5es de pessoas, mas que a previs\u00e3o \u00e9 que cerca de 3 milh\u00f5es sejam beneficiados num primeiro momento. Quem voou nos \u00faltimos 12 meses, por exemplo, n\u00e3o poder\u00e1 ter acesso ao programa.<\/p>\n<p style=\"text-align: justify;\">Ap\u00f3s reuni\u00e3o com o presidente Luiz In\u00e1cio Lula da Silva (PT), Filho disse que o chefe do Executivo ir\u00e1 lan\u00e7ar o Voa Brasil at\u00e9 o meio de fevereiro, data em que ser\u00e3o dados todos os detalhes para ter acesso ao programa.<\/p>\n<p style=\"text-align: justify;\">A ideia \u00e9 que as passagens estejam dispon\u00edveis j\u00e1 no dia do lan\u00e7amento do projeto.<\/p>\n<p style=\"text-align: justify;\">\u201cA gente espera, de todos os aposentados e estudantes do Prouni, atingir num primeiro momento j\u00e1 3 milh\u00f5es de novos CPFs que v\u00e3o viajar. Isso significa incluir quase um pa\u00eds do Uruguai na avia\u00e7\u00e3o brasileira ao longo de 2024. Esse programa vai, sobretudo, ter papel social importante\u201d, disse.<\/p>\n<p style=\"text-align: justify;\">O ministro tem sido o porta-voz de Lula na briga com as companhias a\u00e9reas pelo barateamento das passagens.<\/p>\n<p style=\"text-align: justify;\">Nesta ter\u00e7a-feira, ele afirmou que o governo faz \u201ctodo o esfor\u00e7o\u201d para tentar sensibilizar as a\u00e9reas em rela\u00e7\u00e3o ao pre\u00e7o da passagem e que trabalha para combater o pre\u00e7o abusivo das passagens.<\/p>\n<p style=\"text-align: justify;\">Em dezembro, m\u00eas de alta temporada, quando as passagens disparam, os presidentes das tr\u00eas empresas do setor participaram de evento com Filho para anunciar uma s\u00e9rie de esfor\u00e7os. A Azul disse que vai fornecer 10 milh\u00f5es de assentos por menos de R$ 799 neste ano, enquanto a Gol estimou 15 milh\u00f5es de passagens por at\u00e9 R$ 699.<\/p>\n<p style=\"text-align: justify;\">A Latam, por sua vez, se comprometeu a elevar a oferta de passagens em 10 mil assentos por dia, o que ser\u00e1 feito com aumento de frota. A medida deve dar um f\u00f4lego no momento em que o setor recupera a demanda perdida na pandemia, superando os 100 milh\u00f5es de passageiros transportados de janeiro a novembro, pela primeira vez desde 2019.<\/p>\n<p style=\"text-align: justify;\">Os dados da Anac mostram que o bilhete encareceu nos \u00faltimos anos, saindo de um patamar m\u00e9dio em torno de R$ 500 h\u00e1 menos de uma d\u00e9cada (j\u00e1 com despacho de bagagem inclu\u00edda at\u00e9 2017), para mais de R$ 600 atualmente (fora a cobran\u00e7a separada para quem leva mala). Apesar do avan\u00e7o ao longo do tempo, as tarifas m\u00e9dias mais recentes indicam queda de R$ 657,86 em 2022 para R$ 618 em 2023, nos acumulados de janeiro a outubro.<\/p>\n<p style=\"text-align: justify;\"><span class=\"assinatura_exclusiva\" style=\"font-size: 10pt;\">Matheus Teixeira, Folhapress<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ministro de Portos e Aeroportos, Silvio Costa Filho, afirmou nesta ter\u00e7a-feira (9) que o programa Voa Brasil disponibilizar\u00e1 passagens a R$ 200 e ser\u00e1 voltado a aposentados do INSS (Instituto Nacional do Seguro Social) que ganham at\u00e9 dois sal\u00e1rios m\u00ednimos e estudantes do Prouni. O ministro afirmou que esse p\u00fablico equivale a 20,6 milh\u00f5es [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":701,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-700","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governo anuncia passagem de avi\u00e3o a R$ 200 para ao menos 3 milh\u00f5es de aposentados e estudantes - SITICCAN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/siticcan.com.br\/ba\/index.php\/2024\/01\/10\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo anuncia passagem de avi\u00e3o a R$ 200 para ao menos 3 milh\u00f5es de aposentados e estudantes - SITICCAN\" \/>\n<meta property=\"og:description\" content=\"O ministro de Portos e Aeroportos, Silvio Costa Filho, afirmou nesta ter\u00e7a-feira (9) que o programa Voa Brasil disponibilizar\u00e1 passagens a R$ 200 e ser\u00e1 voltado a aposentados do INSS (Instituto Nacional do Seguro Social) que ganham at\u00e9 dois sal\u00e1rios m\u00ednimos e estudantes do Prouni. O ministro afirmou que esse p\u00fablico equivale a 20,6 milh\u00f5es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/siticcan.com.br\/ba\/index.php\/2024\/01\/10\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\/\" \/>\n<meta property=\"og:site_name\" content=\"SITICCAN\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-10T13:22:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/siticcan.com.br\/ba\/wp-content\/uploads\/2024\/01\/silvio-costa-filho_-vosmar-rosa_mpa-900x615-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"615\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Antonio C Garcez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio C Garcez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/index.php\\\/2024\\\/01\\\/10\\\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/index.php\\\/2024\\\/01\\\/10\\\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\\\/\"},\"author\":{\"name\":\"Antonio C Garcez\",\"@id\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/#\\\/schema\\\/person\\\/54850edda0325b1fb9103f1261d2c2d8\"},\"headline\":\"Governo anuncia passagem de avi\u00e3o a R$ 200 para ao menos 3 milh\u00f5es de aposentados e estudantes\",\"datePublished\":\"2024-01-10T13:22:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/index.php\\\/2024\\\/01\\\/10\\\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\\\/\"},\"wordCount\":486,\"image\":{\"@id\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/index.php\\\/2024\\\/01\\\/10\\\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/silvio-costa-filho_-vosmar-rosa_mpa-900x615-1.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/index.php\\\/2024\\\/01\\\/10\\\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\\\/\",\"url\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/index.php\\\/2024\\\/01\\\/10\\\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\\\/\",\"name\":\"Governo anuncia passagem de avi\u00e3o a R$ 200 para ao menos 3 milh\u00f5es de aposentados e estudantes - SITICCAN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/index.php\\\/2024\\\/01\\\/10\\\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/index.php\\\/2024\\\/01\\\/10\\\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/silvio-costa-filho_-vosmar-rosa_mpa-900x615-1.jpg\",\"datePublished\":\"2024-01-10T13:22:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/#\\\/schema\\\/person\\\/54850edda0325b1fb9103f1261d2c2d8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/index.php\\\/2024\\\/01\\\/10\\\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/index.php\\\/2024\\\/01\\\/10\\\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/index.php\\\/2024\\\/01\\\/10\\\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/silvio-costa-filho_-vosmar-rosa_mpa-900x615-1.jpg\",\"contentUrl\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/silvio-costa-filho_-vosmar-rosa_mpa-900x615-1.jpg\",\"width\":900,\"height\":615,\"caption\":\"Foto: Vosmar Rosa\\\/MPA\\\/Arquivo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/index.php\\\/2024\\\/01\\\/10\\\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governo anuncia passagem de avi\u00e3o a R$ 200 para ao menos 3 milh\u00f5es de aposentados e estudantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/#website\",\"url\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/\",\"name\":\"SITICCAN | SINDICATO DE LUTA | FILIADO A CUT\",\"description\":\"O Sindicato dos Trabalhadores na Ind\u00fastria da Constru\u00e7\u00e3o Civil de Candeias.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/#\\\/schema\\\/person\\\/54850edda0325b1fb9103f1261d2c2d8\",\"name\":\"Antonio C Garcez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d07d79e920fdcbee9f93c580ddba7167d847827d3e13be224aed25d9f6095bc0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d07d79e920fdcbee9f93c580ddba7167d847827d3e13be224aed25d9f6095bc0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d07d79e920fdcbee9f93c580ddba7167d847827d3e13be224aed25d9f6095bc0?s=96&d=mm&r=g\",\"caption\":\"Antonio C Garcez\"},\"url\":\"https:\\\/\\\/siticcan.com.br\\\/ba\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governo anuncia passagem de avi\u00e3o a R$ 200 para ao menos 3 milh\u00f5es de aposentados e estudantes - SITICCAN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/siticcan.com.br\/ba\/index.php\/2024\/01\/10\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\/","og_locale":"pt_BR","og_type":"article","og_title":"Governo anuncia passagem de avi\u00e3o a R$ 200 para ao menos 3 milh\u00f5es de aposentados e estudantes - SITICCAN","og_description":"O ministro de Portos e Aeroportos, Silvio Costa Filho, afirmou nesta ter\u00e7a-feira (9) que o programa Voa Brasil disponibilizar\u00e1 passagens a R$ 200 e ser\u00e1 voltado a aposentados do INSS (Instituto Nacional do Seguro Social) que ganham at\u00e9 dois sal\u00e1rios m\u00ednimos e estudantes do Prouni. O ministro afirmou que esse p\u00fablico equivale a 20,6 milh\u00f5es [&hellip;]","og_url":"https:\/\/siticcan.com.br\/ba\/index.php\/2024\/01\/10\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\/","og_site_name":"SITICCAN","article_published_time":"2024-01-10T13:22:47+00:00","og_image":[{"width":900,"height":615,"url":"https:\/\/siticcan.com.br\/ba\/wp-content\/uploads\/2024\/01\/silvio-costa-filho_-vosmar-rosa_mpa-900x615-1.jpg","type":"image\/jpeg"}],"author":"Antonio C Garcez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio C Garcez","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/siticcan.com.br\/ba\/index.php\/2024\/01\/10\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\/#article","isPartOf":{"@id":"https:\/\/siticcan.com.br\/ba\/index.php\/2024\/01\/10\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\/"},"author":{"name":"Antonio C Garcez","@id":"https:\/\/siticcan.com.br\/ba\/#\/schema\/person\/54850edda0325b1fb9103f1261d2c2d8"},"headline":"Governo anuncia passagem de avi\u00e3o a R$ 200 para ao menos 3 milh\u00f5es de aposentados e estudantes","datePublished":"2024-01-10T13:22:47+00:00","mainEntityOfPage":{"@id":"https:\/\/siticcan.com.br\/ba\/index.php\/2024\/01\/10\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\/"},"wordCount":486,"image":{"@id":"https:\/\/siticcan.com.br\/ba\/index.php\/2024\/01\/10\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\/#primaryimage"},"thumbnailUrl":"https:\/\/siticcan.com.br\/ba\/wp-content\/uploads\/2024\/01\/silvio-costa-filho_-vosmar-rosa_mpa-900x615-1.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/siticcan.com.br\/ba\/index.php\/2024\/01\/10\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\/","url":"https:\/\/siticcan.com.br\/ba\/index.php\/2024\/01\/10\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\/","name":"Governo anuncia passagem de avi\u00e3o a R$ 200 para ao menos 3 milh\u00f5es de aposentados e estudantes - SITICCAN","isPartOf":{"@id":"https:\/\/siticcan.com.br\/ba\/#website"},"primaryImageOfPage":{"@id":"https:\/\/siticcan.com.br\/ba\/index.php\/2024\/01\/10\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\/#primaryimage"},"image":{"@id":"https:\/\/siticcan.com.br\/ba\/index.php\/2024\/01\/10\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\/#primaryimage"},"thumbnailUrl":"https:\/\/siticcan.com.br\/ba\/wp-content\/uploads\/2024\/01\/silvio-costa-filho_-vosmar-rosa_mpa-900x615-1.jpg","datePublished":"2024-01-10T13:22:47+00:00","author":{"@id":"https:\/\/siticcan.com.br\/ba\/#\/schema\/person\/54850edda0325b1fb9103f1261d2c2d8"},"breadcrumb":{"@id":"https:\/\/siticcan.com.br\/ba\/index.php\/2024\/01\/10\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/siticcan.com.br\/ba\/index.php\/2024\/01\/10\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/siticcan.com.br\/ba\/index.php\/2024\/01\/10\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\/#primaryimage","url":"https:\/\/siticcan.com.br\/ba\/wp-content\/uploads\/2024\/01\/silvio-costa-filho_-vosmar-rosa_mpa-900x615-1.jpg","contentUrl":"https:\/\/siticcan.com.br\/ba\/wp-content\/uploads\/2024\/01\/silvio-costa-filho_-vosmar-rosa_mpa-900x615-1.jpg","width":900,"height":615,"caption":"Foto: Vosmar Rosa\/MPA\/Arquivo"},{"@type":"BreadcrumbList","@id":"https:\/\/siticcan.com.br\/ba\/index.php\/2024\/01\/10\/governo-anuncia-passagem-de-aviao-a-r-200-para-ao-menos-3-milhoes-de-aposentados-e-estudantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/siticcan.com.br\/ba\/"},{"@type":"ListItem","position":2,"name":"Governo anuncia passagem de avi\u00e3o a R$ 200 para ao menos 3 milh\u00f5es de aposentados e estudantes"}]},{"@type":"WebSite","@id":"https:\/\/siticcan.com.br\/ba\/#website","url":"https:\/\/siticcan.com.br\/ba\/","name":"SITICCAN | SINDICATO DE LUTA | FILIADO A CUT","description":"O Sindicato dos Trabalhadores na Ind\u00fastria da Constru\u00e7\u00e3o Civil de Candeias.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/siticcan.com.br\/ba\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/siticcan.com.br\/ba\/#\/schema\/person\/54850edda0325b1fb9103f1261d2c2d8","name":"Antonio C Garcez","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d07d79e920fdcbee9f93c580ddba7167d847827d3e13be224aed25d9f6095bc0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d07d79e920fdcbee9f93c580ddba7167d847827d3e13be224aed25d9f6095bc0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d07d79e920fdcbee9f93c580ddba7167d847827d3e13be224aed25d9f6095bc0?s=96&d=mm&r=g","caption":"Antonio C Garcez"},"url":"https:\/\/siticcan.com.br\/ba\/index.php\/author\/redacao\/"}]}},"_links":{"self":[{"href":"https:\/\/siticcan.com.br\/ba\/index.php\/wp-json\/wp\/v2\/posts\/700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/siticcan.com.br\/ba\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/siticcan.com.br\/ba\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/siticcan.com.br\/ba\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/siticcan.com.br\/ba\/index.php\/wp-json\/wp\/v2\/comments?post=700"}],"version-history":[{"count":1,"href":"https:\/\/siticcan.com.br\/ba\/index.php\/wp-json\/wp\/v2\/posts\/700\/revisions"}],"predecessor-version":[{"id":702,"href":"https:\/\/siticcan.com.br\/ba\/index.php\/wp-json\/wp\/v2\/posts\/700\/revisions\/702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/siticcan.com.br\/ba\/index.php\/wp-json\/wp\/v2\/media\/701"}],"wp:attachment":[{"href":"https:\/\/siticcan.com.br\/ba\/index.php\/wp-json\/wp\/v2\/media?parent=700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/siticcan.com.br\/ba\/index.php\/wp-json\/wp\/v2\/categories?post=700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/siticcan.com.br\/ba\/index.php\/wp-json\/wp\/v2\/tags?post=700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}